{"id":396,"date":"2011-11-13T19:02:32","date_gmt":"2011-11-13T19:02:32","guid":{"rendered":"http:\/\/www.biolaster.com\/blog-kinesiotape\/396"},"modified":"2016-12-22T12:24:44","modified_gmt":"2016-12-22T12:24:44","slug":"test-25","status":"publish","type":"post","link":"http:\/\/www.biolaster.com\/blogs\/kinesiotape\/2011\/11\/13\/test-25\/","title":{"rendered":"ONCE del ONCE del dosmil-ONCE"},"content":{"rendered":"<p><img decoding=\"async\" src=\"\/blogs\/wp-content\/uploads\/sites\/3\/doc\/marino\" align=\"right\" vspace=\"8\" hspace=\"8\" \/><br \/>\nDe la mano del que fuera nuestro director deportivo, Manuel Saiz, surgi\u00f3 a principios de a\u00f1o la idea de juntarnos el ONCE del ONCE del dos mil-ONCE todos los que en su momento formamos parte de aquel hist\u00f3rico equipo de ciclismo desde 1989 , momento de su formaci\u00f3n, hasta el a\u00f1o 2003, momento de su desaparici\u00f3n. Y tras una gran aceptaci\u00f3n as\u00ed fue, de tal manera que tanto corredores como auxiliares nos juntamos por fin y pasamos un gran d\u00eda-noche recordando viejos tiempos e imborrables batallas. Fuimos un gran grupo tanto a nivel personal como profesional sin duda y prueba de ello es que tantos a\u00f1os despu\u00e9s han llegado ciclistas desde Suiza, Holanda, Chequia, Italia, Dinamarca\u2026para volver a vernos. Aprovech\u00e9 el momento para hacernos una foto de recuerdo  con el maillot conmemorativo con nuestros nombres junto a mi amigo Marino Lejarreta, prologuista distinguido del primer libro Kinesiology Tape Manual, precisamente con \u00e9l,  por ser el primer ciclista profesional del equipo que nos dej\u00f3 experimentar con las primeras cintas de Kinesiotape que cayeron en mis manos all\u00e1 por 1990 en el Mundial de Jap\u00f3n (Utsunomiya).<\/p>\n<p><img decoding=\"async\" src=\"\/blogs\/wp-content\/uploads\/sites\/3\/doc\/once4\" align=\"right\" vspace=\"8\" hspace=\"8\" \/><br \/>\nAs\u00ed que tras un d\u00eda tan intenso ( partido de f\u00fatbol 7 incluido con resultado final de ONCE a ONCE) que termin\u00f3 muy tarde, unos cuantos padecieron agujetas fruto del desentreno y a  ra\u00edz  de ello se me ocurri\u00f3 plasmar hoy una buena aplicaci\u00f3n de Kinesiotape ,dentro de las varias posibilidades que existen, precisamente  para las agujetas o la carga muscular general sobre el cuadriceps , posterior a sobreesfuerzos. Una aplicaci\u00f3n muy efectiva, pr\u00e1cticamente inmediata,  y sencilla de realizar. <\/p>\n<p><img decoding=\"async\" src=\"\/blogs\/wp-content\/uploads\/sites\/3\/doc\/ONCE1\" align=\"right\" vspace=\"8\" hspace=\"8\" \/><br \/>\nLa T\u00e9cnica empleada ser\u00e1 Muscular y la realizaremos con dos tiras en Y desde las inserciones en Vasto Interno y Vasto Externo con anclajes de inicio sin tensi\u00f3n con la pierna en carga.<\/p>\n<p><img decoding=\"async\" src=\"\/blogs\/wp-content\/uploads\/sites\/3\/doc\/ONCE2\" align=\"right\" vspace=\"8\" hspace=\"8\" \/> <br \/>\nSeguidamente pedimos una flexi\u00f3n mantenida de la misma y deslizamos la primera cinta en Y desde la inserci\u00f3n del Vasto Externo hacia su origen (en el lateral del Trocanter Mayor) sin dar tensi\u00f3n a la venda y abarcando la parte externa de dicho m\u00fasculo y la central del Recto Anterior. Una vez terminado procedemos a realizar la misma operaci\u00f3n con la segunda cinta en Y desde Vasto Interno hacia su origen (linea intertrocant\u00e9rea ) , siempre con la pierna en flexi\u00f3n, abarcando el Recto Anterior con la tira externa pero sin solaparse con la primera venda , y  el Vasto Interno con la tira interna.<\/p>\n<p><img decoding=\"async\" src=\"\/blogs\/wp-content\/uploads\/sites\/3\/doc\/ONCE3\" align=\"right\" vspace=\"8\" hspace=\"8\" \/><br \/>\nAs\u00ed que no desaprovechamos ni las fiestas para poder seguir aportando ideas en este blog de kinesiotape\u2026 ,eso s\u00ed, para los incondicionales de las aplicaciones en base a los posibles colores decir que la aqu\u00ed mostrada est\u00e1 hecha con cinta amarilla y negra porque\u2026 eran los colores, nuestros colores oficiales , los de nuestro maillot, uno de los m\u00e1s bonitos y ya  m\u00edticos de toda la historia del ciclismo profesional. \u00a1Gracias Manolo!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De la mano del que fuera nuestro director deportivo, Manuel Saiz, surgi\u00f3 a principios de a\u00f1o la<br \/>\nidea de juntarnos el ONCE del ONCE del dos mil-ONCE todos los que en su momento formamos parte de<br \/>\naquel hist\u00f3rico equipo de ciclismo desde 1989 , momento &#8230;&#8230;<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v14.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ONCE del ONCE del dosmil-ONCE - Kinesiology Tape<\/title>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<meta name=\"googlebot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta name=\"bingbot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.biolaster.com\/blogs\/kinesiotape\/2011\/11\/13\/test-25\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ONCE del ONCE del dosmil-ONCE - Kinesiology Tape\" \/>\n<meta property=\"og:description\" content=\"De la mano del que fuera nuestro director deportivo, Manuel Saiz, surgi\u00f3 a principios de a\u00f1o la idea de juntarnos el ONCE del ONCE del dos mil-ONCE todos los que en su momento formamos parte de aquel hist\u00f3rico equipo de ciclismo desde 1989 , momento ......\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.biolaster.com\/blogs\/kinesiotape\/2011\/11\/13\/test-25\/\" \/>\n<meta property=\"og:site_name\" content=\"Kinesiology Tape\" \/>\n<meta property=\"article:published_time\" content=\"2011-11-13T19:02:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-12-22T12:24:44+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.biolaster.com\/blogs\/wp-content\/uploads\/sites\/3\/doc\/marino\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.biolaster.com\/blogs\/kinesiotape\/#website\",\"url\":\"http:\/\/www.biolaster.com\/blogs\/kinesiotape\/\",\"name\":\"Kinesiology Tape\",\"description\":\"Comentarios sobre diferentes aspectos ligados al Kinesiology Tape\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"http:\/\/www.biolaster.com\/blogs\/kinesiotape\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.biolaster.com\/blogs\/kinesiotape\/2011\/11\/13\/test-25\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"\/blogs\/wp-content\/uploads\/sites\/3\/doc\/marino\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.biolaster.com\/blogs\/kinesiotape\/2011\/11\/13\/test-25\/#webpage\",\"url\":\"http:\/\/www.biolaster.com\/blogs\/kinesiotape\/2011\/11\/13\/test-25\/\",\"name\":\"ONCE del ONCE del dosmil-ONCE - Kinesiology Tape\",\"isPartOf\":{\"@id\":\"http:\/\/www.biolaster.com\/blogs\/kinesiotape\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.biolaster.com\/blogs\/kinesiotape\/2011\/11\/13\/test-25\/#primaryimage\"},\"datePublished\":\"2011-11-13T19:02:32+00:00\",\"dateModified\":\"2016-12-22T12:24:44+00:00\",\"author\":{\"@id\":\"http:\/\/www.biolaster.com\/blogs\/kinesiotape\/#\/schema\/person\/2256b5038440a37f419f7017a65a4fec\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.biolaster.com\/blogs\/kinesiotape\/2011\/11\/13\/test-25\/\"]}]},{\"@type\":[\"Person\"],\"@id\":\"http:\/\/www.biolaster.com\/blogs\/kinesiotape\/#\/schema\/person\/2256b5038440a37f419f7017a65a4fec\",\"name\":\"txema\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.biolaster.com\/blogs\/kinesiotape\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"http:\/\/1.gravatar.com\/avatar\/a6ba1bb5a7aabc400b738cc20da2feda?s=96&d=mm&r=g\",\"caption\":\"txema\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/www.biolaster.com\/blogs\/kinesiotape\/wp-json\/wp\/v2\/posts\/396"}],"collection":[{"href":"http:\/\/www.biolaster.com\/blogs\/kinesiotape\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.biolaster.com\/blogs\/kinesiotape\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.biolaster.com\/blogs\/kinesiotape\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"http:\/\/www.biolaster.com\/blogs\/kinesiotape\/wp-json\/wp\/v2\/comments?post=396"}],"version-history":[{"count":1,"href":"http:\/\/www.biolaster.com\/blogs\/kinesiotape\/wp-json\/wp\/v2\/posts\/396\/revisions"}],"predecessor-version":[{"id":473,"href":"http:\/\/www.biolaster.com\/blogs\/kinesiotape\/wp-json\/wp\/v2\/posts\/396\/revisions\/473"}],"wp:attachment":[{"href":"http:\/\/www.biolaster.com\/blogs\/kinesiotape\/wp-json\/wp\/v2\/media?parent=396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.biolaster.com\/blogs\/kinesiotape\/wp-json\/wp\/v2\/categories?post=396"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.biolaster.com\/blogs\/kinesiotape\/wp-json\/wp\/v2\/tags?post=396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}